{"id":10129,"date":"2015-10-23T11:18:37","date_gmt":"2015-10-23T11:18:37","guid":{"rendered":"http:\/\/setramoperadorlogisticomultimodal.com\/?p=1610"},"modified":"2015-10-23T11:18:37","modified_gmt":"2015-10-23T11:18:37","slug":"las-ventas-de-coches-usados-aumentan-casi-un-12-hasta-septiembre","status":"publish","type":"post","link":"https:\/\/www.setram.com\/en\/las-ventas-de-coches-usados-aumentan-casi-un-12-hasta-septiembre\/","title":{"rendered":"Las ventas de coches usados aumentan casi un 12% hasta septiembre"},"content":{"rendered":"<p style=\"text-align:justify;\"><strong>Barcelona, 23 de octubre del 2015.-<\/strong> \u00a0Las ventas de coches usados han aumentado un 11,6% en los nueve primeros meses del a\u00f1o respecto al mismo periodo del ejercicio anterior, con un total de 1.306.973 transacciones hechas, seg\u00fan datos del Instituto de Estudios de Automoci\u00f3n (IEA), para la Federaci\u00f3n de Asociaciones de Concesionarios de la Automoci\u00f3n (FACONAUTO).\u00a0Por edades, las transferencias de usados de hasta tres a\u00f1os crec\u00edan un 21,7%, mientras que los que van de tres a cinco a\u00f1os repuntaban un 19,7%. Los modelos de entre cinco y diez a\u00f1os s\u00f3lo se incrementaban un 1,1%, y los mayores de diez lo hac\u00edan un 12,7%. De esta manera, siguen siendo los usados \u201cj\u00f3venes\u201d los que impulsan un mercado que se mantiene s\u00f3lido, aunque el grueso (53%) de las transacciones todav\u00eda tiene como protagonistas a esos coches viejos de m\u00e1s de diez a\u00f1os.<\/p>\n<p style=\"text-align:justify;\">\u201cEl mercado de veh\u00edculos de segunda mano est\u00e1 claramente polarizado, siendo los coches seminuevos los que con m\u00e1s fuerza crecen en ventas, unas ventas que, sin embargo, son en su mayor\u00eda copadas por modelos que superan los diez a\u00f1os de edad. Una de las consecuencias de esta tendencia, adem\u00e1s del envejecimiento de parque, es el incremento en el valor residual de los usados que se venden en nuestro pa\u00eds, que en el \u00faltimo a\u00f1o se han encarecido un 19%, situ\u00e1ndose en 10.651 euros de media\u201d, ha indicado el presidente de Faconauto, Jaume Roura. Precisamente, el presidente de la patronal de los concesionarios\u00a0ha destacado hoy desde Navarra los cambios que se deber\u00edan emprender en la industria del autom\u00f3vil:<\/p>\n<p><iframe title=\"Desayunos Empresariales con Jaume Roura en Navarra Tv\" width=\"800\" height=\"600\" src=\"https:\/\/www.youtube.com\/embed\/QI72yi6Nwjc?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p style=\"text-align:justify;\">En este mismo sentido, el precio que pagan finalmente los compradores de coches usados tambi\u00e9n sigue subiendo. En concreto, en septiembre lo hizo un 6,6% respecto al mismo mes del a\u00f1o anterior, hasta los 13.013 euros, seg\u00fan datos del portal coches.net.<\/p>\n<p style=\"text-align:justify;\"><strong>Desglose por Comunidades Aut\u00f3nomas<\/strong><\/p>\n<p style=\"text-align:justify;\">Por comunidades aut\u00f3nomas, Baleares es donde m\u00e1s subieron las transferencias hasta agosto, con un crecimiento del 26,2%, le siguen Andaluc\u00eda, con un incremento del 14,4%, la Comunidad de Madrid, con un 13%, y Cantabria, con un 12,2%. En la misma l\u00ednea est\u00e1 la Comunidad Valenciana un 11,8%, Murcia un 11,5%, Asturias un 11,4%, Extremadura un 11,2%, Arag\u00f3n un 11,1% y Catalu\u00f1a un 11%.<\/p>\n<p style=\"text-align:justify;\">A m\u00e1s distancia le siguen Canarias (+10,5%), La Rioja (+10,2%), Galicia (+9,4%), Catilla y Le\u00f3n (+9,3%), Navarra (+9,1%), Castilla-La Mancha (+8,4%), Pa\u00eds Vasco (+4,6%) y Ceuta\/Melilla (+3,9%).<\/p>\n<p style=\"text-align:justify;\">Faconauto es la patronal que integra las asociaciones de concesionarios oficiales de las marcas automovil\u00edsticas, de veh\u00edculos industriales y de maquinaria agr\u00edcola presentes en el mercado espa\u00f1ol. En la actualidad representa los intereses de 2.232 concesionarios de turismos y 282 de veh\u00edculos industriales y maquinaria agr\u00edcola de los que dependen aproximadamente las 1.810 empresas del segundo nivel de distribuci\u00f3n (agencias y servicios oficiales), lo que totaliza m\u00e1s de 4.100 pymes de automoci\u00f3n. Estas empresas generan 137.000 empleos directos y una facturaci\u00f3n de 25.545 millones de euros anuales.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Barcelona, 23 de octubre del 2015.- \u00a0Las ventas de coches usados han aumentado un 11,6% en los nueve primeros meses del a\u00f1o respecto al mismo periodo del ejercicio anterior, con un total de 1.306.973 transacciones hechas, seg\u00fan datos del Instituto de Estudios de Automoci\u00f3n (IEA), para la Federaci\u00f3n de Asociaciones de Concesionarios de la Automoci\u00f3n [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":1100,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_yoast_wpseo_title":"","_yoast_wpseo_metadesc":"","footnotes":""},"categories":[1854],"tags":[1855,21,1845,56,1846,1856,26,1849,1857,27,160,573,29,416,1858,1861,1862,1859,1860],"class_list":["post-10129","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aumentan-ventas-coches-usados-set-2015","tag-camiones-transporte-coches-usados","tag-distribucion-nacional-coches","tag-flotas-buyback","tag-logistica-integral-automovil","tag-logistica-multimodal","tag-operador-logisticos-multimodal","tag-portavehiculos","tag-remarketing-vehiculos","tag-reno-a-car","tag-setram","tag-terminal-automoviles-setram","tag-terminales-automoviles","tag-transporte-coches","tag-transporte-coches-usados","tag-transporte-vehiculos-ocasion","tag-ventas-coches-de-ocasion","tag-ventas-coches-usados-set-2015","tag-video-jaume-roura-sobre-sector-automovil-los-cambios","tag-video-presidente-faconauto"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Las ventas de coches usados aumentan casi un 12% hasta septiembre - Log\u00edstica Automoci\u00f3n &amp; Campas Veh\u00edculos | SETRAM<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.setram.com\/en\/las-ventas-de-coches-usados-aumentan-casi-un-12-hasta-septiembre\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Las ventas de coches usados aumentan casi un 12% hasta septiembre - Log\u00edstica Automoci\u00f3n &amp; Campas Veh\u00edculos | SETRAM\" \/>\n<meta property=\"og:description\" content=\"Barcelona, 23 de octubre del 2015.- \u00a0Las ventas de coches usados han aumentado un 11,6% en los nueve primeros meses del a\u00f1o respecto al mismo periodo del ejercicio anterior, con un total de 1.306.973 transacciones hechas, seg\u00fan datos del Instituto de Estudios de Automoci\u00f3n (IEA), para la Federaci\u00f3n de Asociaciones de Concesionarios de la Automoci\u00f3n [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.setram.com\/en\/las-ventas-de-coches-usados-aumentan-casi-un-12-hasta-septiembre\/\" \/>\n<meta property=\"og:site_name\" content=\"Log\u00edstica Automoci\u00f3n &amp; Campas Veh\u00edculos | SETRAM\" \/>\n<meta property=\"article:published_time\" content=\"2015-10-23T11:18:37+00:00\" \/>\n<meta name=\"author\" content=\"SETRAM L\u00edder en Log\u00edstica de Automoci\u00f3n en Europa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@_setram\" \/>\n<meta name=\"twitter:site\" content=\"@_setram\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"SETRAM L\u00edder en Log\u00edstica de Automoci\u00f3n en Europa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.setram.com\\\/en\\\/las-ventas-de-coches-usados-aumentan-casi-un-12-hasta-septiembre\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.setram.com\\\/en\\\/las-ventas-de-coches-usados-aumentan-casi-un-12-hasta-septiembre\\\/\"},\"author\":{\"name\":\"SETRAM L\u00edder en Log\u00edstica de Automoci\u00f3n en Europa\",\"@id\":\"https:\\\/\\\/www.setram.com\\\/en\\\/#\\\/schema\\\/person\\\/a5183775ce67dd23659a88233b83cd4d\"},\"headline\":\"Las ventas de coches usados aumentan casi un 12% hasta septiembre\",\"datePublished\":\"2015-10-23T11:18:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.setram.com\\\/en\\\/las-ventas-de-coches-usados-aumentan-casi-un-12-hasta-septiembre\\\/\"},\"wordCount\":515,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\\\/\\\/www.setram.com\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.setram.com\\\/en\\\/las-ventas-de-coches-usados-aumentan-casi-un-12-hasta-septiembre\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"keywords\":[\"camiones transporte coches usados\",\"DISTRIBUCI\u00d3N NACIONAL COCHES\",\"flotas buyback\",\"Log\u00edstica integral autom\u00f3vil\",\"log\u00edstica multimodal\",\"operador log\u00edsticos multimodal\",\"PORTAVEH\u00cdCULOS\",\"remarketing veh\u00edculos\",\"reno-a-car\",\"SETRAM\",\"Terminal Autom\u00f3viles Setram\",\"terminales autom\u00f3viles\",\"TRANSPORTE COCHES\",\"transporte coches usados\",\"transporte veh\u00edculos ocasi\u00f3n\",\"ventas coches de ocasi\u00f3n\",\"ventas coches usados set 2015\",\"v\u00eddeo Jaume Roura sobre sector autom\u00f3vil los cambios\",\"v\u00eddeo presidente Faconauto\"],\"articleSection\":[\"AUMENTAN VENTAS COCHES USADOS SET 2015\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.setram.com\\\/en\\\/las-ventas-de-coches-usados-aumentan-casi-un-12-hasta-septiembre\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.setram.com\\\/en\\\/las-ventas-de-coches-usados-aumentan-casi-un-12-hasta-septiembre\\\/\",\"url\":\"https:\\\/\\\/www.setram.com\\\/en\\\/las-ventas-de-coches-usados-aumentan-casi-un-12-hasta-septiembre\\\/\",\"name\":\"Las ventas de coches usados aumentan casi un 12% hasta septiembre - Log\u00edstica Automoci\u00f3n &amp; Campas Veh\u00edculos | SETRAM\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.setram.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.setram.com\\\/en\\\/las-ventas-de-coches-usados-aumentan-casi-un-12-hasta-septiembre\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.setram.com\\\/en\\\/las-ventas-de-coches-usados-aumentan-casi-un-12-hasta-septiembre\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2015-10-23T11:18:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.setram.com\\\/en\\\/las-ventas-de-coches-usados-aumentan-casi-un-12-hasta-septiembre\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.setram.com\\\/en\\\/las-ventas-de-coches-usados-aumentan-casi-un-12-hasta-septiembre\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.setram.com\\\/en\\\/las-ventas-de-coches-usados-aumentan-casi-un-12-hasta-septiembre\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.setram.com\\\/en\\\/las-ventas-de-coches-usados-aumentan-casi-un-12-hasta-septiembre\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.setram.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Las ventas de coches usados aumentan casi un 12% hasta septiembre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.setram.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.setram.com\\\/en\\\/\",\"name\":\"Log\u00edstica Automoci\u00f3n & Campas Veh\u00edculos | SETRAM\",\"description\":\"Operador Multimodal especializado en Log\u00edstica de Automoci\u00f3n con certificado Ambiental ISO. Comprometidos con el medio ambiente gracias a su gesti\u00f3n energ\u00e9tica.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.setram.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.setram.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.setram.com\\\/en\\\/#organization\",\"name\":\"Log\u00edstica Automoci\u00f3n & Campas Veh\u00edculos | SETRAM\",\"url\":\"https:\\\/\\\/www.setram.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.setram.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.setram.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/logo-setram.jpg\",\"contentUrl\":\"https:\\\/\\\/www.setram.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/logo-setram.jpg\",\"width\":484,\"height\":107,\"caption\":\"Log\u00edstica Automoci\u00f3n & Campas Veh\u00edculos | SETRAM\"},\"image\":{\"@id\":\"https:\\\/\\\/www.setram.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/_setram\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/setram-s-a-\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC5j125Vd5dvi3ZCfMXBgNzg\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.setram.com\\\/en\\\/#\\\/schema\\\/person\\\/a5183775ce67dd23659a88233b83cd4d\",\"name\":\"SETRAM L\u00edder en Log\u00edstica de Automoci\u00f3n en Europa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.setram.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/favicon-setram.png\",\"url\":\"https:\\\/\\\/www.setram.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/favicon-setram.png\",\"contentUrl\":\"https:\\\/\\\/www.setram.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/favicon-setram.png\",\"caption\":\"SETRAM L\u00edder en Log\u00edstica de Automoci\u00f3n en Europa\"},\"sameAs\":[\"https:\\\/\\\/es.linkedin.com\\\/company\\\/setram-s-a-\"],\"url\":\"https:\\\/\\\/www.setram.com\\\/en\\\/author\\\/setram\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Las ventas de coches usados aumentan casi un 12% hasta septiembre - Log\u00edstica Automoci\u00f3n &amp; Campas Veh\u00edculos | SETRAM","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.setram.com\/en\/las-ventas-de-coches-usados-aumentan-casi-un-12-hasta-septiembre\/","og_locale":"en_US","og_type":"article","og_title":"Las ventas de coches usados aumentan casi un 12% hasta septiembre - Log\u00edstica Automoci\u00f3n &amp; Campas Veh\u00edculos | SETRAM","og_description":"Barcelona, 23 de octubre del 2015.- \u00a0Las ventas de coches usados han aumentado un 11,6% en los nueve primeros meses del a\u00f1o respecto al mismo periodo del ejercicio anterior, con un total de 1.306.973 transacciones hechas, seg\u00fan datos del Instituto de Estudios de Automoci\u00f3n (IEA), para la Federaci\u00f3n de Asociaciones de Concesionarios de la Automoci\u00f3n [&hellip;]","og_url":"https:\/\/www.setram.com\/en\/las-ventas-de-coches-usados-aumentan-casi-un-12-hasta-septiembre\/","og_site_name":"Log\u00edstica Automoci\u00f3n &amp; Campas Veh\u00edculos | SETRAM","article_published_time":"2015-10-23T11:18:37+00:00","author":"SETRAM L\u00edder en Log\u00edstica de Automoci\u00f3n en Europa","twitter_card":"summary_large_image","twitter_creator":"@_setram","twitter_site":"@_setram","twitter_misc":{"Written by":"SETRAM L\u00edder en Log\u00edstica de Automoci\u00f3n en Europa","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.setram.com\/en\/las-ventas-de-coches-usados-aumentan-casi-un-12-hasta-septiembre\/#article","isPartOf":{"@id":"https:\/\/www.setram.com\/en\/las-ventas-de-coches-usados-aumentan-casi-un-12-hasta-septiembre\/"},"author":{"name":"SETRAM L\u00edder en Log\u00edstica de Automoci\u00f3n en Europa","@id":"https:\/\/www.setram.com\/en\/#\/schema\/person\/a5183775ce67dd23659a88233b83cd4d"},"headline":"Las ventas de coches usados aumentan casi un 12% hasta septiembre","datePublished":"2015-10-23T11:18:37+00:00","mainEntityOfPage":{"@id":"https:\/\/www.setram.com\/en\/las-ventas-de-coches-usados-aumentan-casi-un-12-hasta-septiembre\/"},"wordCount":515,"commentCount":1,"publisher":{"@id":"https:\/\/www.setram.com\/en\/#organization"},"image":{"@id":"https:\/\/www.setram.com\/en\/las-ventas-de-coches-usados-aumentan-casi-un-12-hasta-septiembre\/#primaryimage"},"thumbnailUrl":"","keywords":["camiones transporte coches usados","DISTRIBUCI\u00d3N NACIONAL COCHES","flotas buyback","Log\u00edstica integral autom\u00f3vil","log\u00edstica multimodal","operador log\u00edsticos multimodal","PORTAVEH\u00cdCULOS","remarketing veh\u00edculos","reno-a-car","SETRAM","Terminal Autom\u00f3viles Setram","terminales autom\u00f3viles","TRANSPORTE COCHES","transporte coches usados","transporte veh\u00edculos ocasi\u00f3n","ventas coches de ocasi\u00f3n","ventas coches usados set 2015","v\u00eddeo Jaume Roura sobre sector autom\u00f3vil los cambios","v\u00eddeo presidente Faconauto"],"articleSection":["AUMENTAN VENTAS COCHES USADOS SET 2015"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.setram.com\/en\/las-ventas-de-coches-usados-aumentan-casi-un-12-hasta-septiembre\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.setram.com\/en\/las-ventas-de-coches-usados-aumentan-casi-un-12-hasta-septiembre\/","url":"https:\/\/www.setram.com\/en\/las-ventas-de-coches-usados-aumentan-casi-un-12-hasta-septiembre\/","name":"Las ventas de coches usados aumentan casi un 12% hasta septiembre - Log\u00edstica Automoci\u00f3n &amp; Campas Veh\u00edculos | SETRAM","isPartOf":{"@id":"https:\/\/www.setram.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.setram.com\/en\/las-ventas-de-coches-usados-aumentan-casi-un-12-hasta-septiembre\/#primaryimage"},"image":{"@id":"https:\/\/www.setram.com\/en\/las-ventas-de-coches-usados-aumentan-casi-un-12-hasta-septiembre\/#primaryimage"},"thumbnailUrl":"","datePublished":"2015-10-23T11:18:37+00:00","breadcrumb":{"@id":"https:\/\/www.setram.com\/en\/las-ventas-de-coches-usados-aumentan-casi-un-12-hasta-septiembre\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.setram.com\/en\/las-ventas-de-coches-usados-aumentan-casi-un-12-hasta-septiembre\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.setram.com\/en\/las-ventas-de-coches-usados-aumentan-casi-un-12-hasta-septiembre\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/www.setram.com\/en\/las-ventas-de-coches-usados-aumentan-casi-un-12-hasta-septiembre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.setram.com\/en\/"},{"@type":"ListItem","position":2,"name":"Las ventas de coches usados aumentan casi un 12% hasta septiembre"}]},{"@type":"WebSite","@id":"https:\/\/www.setram.com\/en\/#website","url":"https:\/\/www.setram.com\/en\/","name":"Log\u00edstica Automoci\u00f3n & Campas Veh\u00edculos | SETRAM","description":"Operador Multimodal especializado en Log\u00edstica de Automoci\u00f3n con certificado Ambiental ISO. Comprometidos con el medio ambiente gracias a su gesti\u00f3n energ\u00e9tica.","publisher":{"@id":"https:\/\/www.setram.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.setram.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.setram.com\/en\/#organization","name":"Log\u00edstica Automoci\u00f3n & Campas Veh\u00edculos | SETRAM","url":"https:\/\/www.setram.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.setram.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.setram.com\/wp-content\/uploads\/2025\/05\/logo-setram.jpg","contentUrl":"https:\/\/www.setram.com\/wp-content\/uploads\/2025\/05\/logo-setram.jpg","width":484,"height":107,"caption":"Log\u00edstica Automoci\u00f3n & Campas Veh\u00edculos | SETRAM"},"image":{"@id":"https:\/\/www.setram.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/_setram","https:\/\/www.linkedin.com\/company\/setram-s-a-","https:\/\/www.youtube.com\/channel\/UC5j125Vd5dvi3ZCfMXBgNzg"]},{"@type":"Person","@id":"https:\/\/www.setram.com\/en\/#\/schema\/person\/a5183775ce67dd23659a88233b83cd4d","name":"SETRAM L\u00edder en Log\u00edstica de Automoci\u00f3n en Europa","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.setram.com\/wp-content\/uploads\/2025\/05\/favicon-setram.png","url":"https:\/\/www.setram.com\/wp-content\/uploads\/2025\/05\/favicon-setram.png","contentUrl":"https:\/\/www.setram.com\/wp-content\/uploads\/2025\/05\/favicon-setram.png","caption":"SETRAM L\u00edder en Log\u00edstica de Automoci\u00f3n en Europa"},"sameAs":["https:\/\/es.linkedin.com\/company\/setram-s-a-"],"url":"https:\/\/www.setram.com\/en\/author\/setram\/"}]}},"_links":{"self":[{"href":"https:\/\/www.setram.com\/en\/wp-json\/wp\/v2\/posts\/10129","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.setram.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.setram.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.setram.com\/en\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.setram.com\/en\/wp-json\/wp\/v2\/comments?post=10129"}],"version-history":[{"count":0,"href":"https:\/\/www.setram.com\/en\/wp-json\/wp\/v2\/posts\/10129\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.setram.com\/en\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/www.setram.com\/en\/wp-json\/wp\/v2\/media?parent=10129"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.setram.com\/en\/wp-json\/wp\/v2\/categories?post=10129"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.setram.com\/en\/wp-json\/wp\/v2\/tags?post=10129"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}